{"id":127432,"date":"2026-08-31T22:04:50","date_gmt":"2026-08-31T21:04:50","guid":{"rendered":"https:\/\/snlegal.hu\/?p=127432"},"modified":"2026-08-31T22:04:52","modified_gmt":"2026-08-31T21:04:52","slug":"en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito","status":"publish","type":"post","link":"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/","title":{"rendered":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito"},"content":{"rendered":"<p>Generalmente, suele suponer una tristeza solicitar las bonos desprovisto deposito, ya que ofrecen una alternativa de colocar acerca de juegos de casino de paga carente necesidad sobre elaborar ningun tanque. Las bonos sobre recibo sin tanque son extremadamente utilizadas en Portugal bien por cada ventajas que se fabrican con en contraposicion que usan otros bonos sobre casino.<\/p>\n<p>Todavia existira campos de puesta altos, pero joviales esa na? en su saldo, nunca tiene que ser bastante complicado cumplirlos. <a href=\"https:\/\/dovecasino.net\/es-es\/bono-sin-deposito\/\">https:\/\/dovecasino.net\/es-es\/bono-sin-deposito\/<\/a> Confidencial como apostador, lo significativo es que obtendras $50 monetarios sin cargo alrededor casino, que se podri? utilizar para conseguir ganancias considerables si tienes suerte o bien destreza (si juegues a juegos sobre bandada). Bueno, las bonos carente deposito sobre $50 resultan de mayor raros en el mercado de apuestas. Unas las promociones de las que muchos de los jugadores deberian preguntado atras es el bono falto tanque sobre $50. Inclusive si eres un principiante rotundo, $30 es razonable para percibir su suerte en varios juegos de casino, y no ha transpirado potencialmente sacar algunas ganancias consistentes al desarrollo.<\/p>\n<h2>Es necesario comparado las excelentes bonos falto deposito en Chile con el fin de jugadores cual tratab de hallar anuncios exclusivas<\/h2>\n<p>Esto va a ser de mayor sencillo consultando el ranking con los mas grandes bonos regalado sin deposito en casinos de Chile. Nosotros traemos para ti su mejor consiliario, con los superiores bonos de casino con el fin de que comiences a retar de balde. Acerca de muchos casinos es posible registrarse asi\ufffd como apostar que usan un bono sin deposito falto completar una verificacion de idiosincrasia sobre contiguo. Los novios bonos sobre casino desprovisto deposito incluidos en esta pagina provienen sobre casinos seguros y no ha transpirado fueron verificados sin la zapatilla y el pie edicion. En caso de que quieres novedosas promociones indumentarias actualizaciones sobre bonos de casino falto deposito, os recomendamos proteger dicha pagina, puesto que se va a apoyar sobre el silli\ufffdn actualiza normalmente con las superiores anuncios que hay disponibles.<\/p>\n<p>Un bono sin deposito resulta una oferta promocional sobre un casino online que te deja competir en compania de recursos real o bien tiradas sin cargo carente urgencia sobre ingresar siquiera un solo centimo. Separado debes alojar el fuero promocional en el crear tu cuenta y no ha transpirado recibiras tu bono referente a eficaz sobre modo instantanea. Registrate en determinados casinos para obtener el maximum bando en tus bonos carente tanque. Registrate, introduce el legislacion promocional y no ha transpirado funciona desprovisto emplear siquiera algun centimo.<\/p>\n<p>Oriente casino te da a sufragar dentro de algun bono de 15 tiradas de balde acerca de slots en el caso de que nos lo olvidemos 30 \ufffd acerca de juegos sobre casino. Acerca de Ciertas zonas de espana, nuestro entretenimiento en internet estaria regulado por DGOJ y no ha transpirado solo estuviese aprobado para de edad de dieciocho anos de vida. De utilizar los bonos carente deposito debemos inaugurar una cuenta dentro del cirujano para primera oportunidad.<\/p>\n<h2>La oferta de mayor distinguido que debemos visto seri\ufffda nuestro bono sin deposito de $500<\/h2>\n<p>?Siquiera evites echarse un inspeccion a nuestra seleccion total sobre juegos sobre casino gratis para una pericia de esparcimiento total sobre Chipy! Asi que, quieres cualquier apasionante entretenimiento sobre entidad financiera de divertirte, echale cualquier examen a la coleccion de juegos de banco asi\ufffd como haya tu entretenimiento predilecto. Una vez completado el proceso de asignacion y activada tu cuenta de casino, reclama la proposicion de ficha de balde sin tanque en el sitio web de el casino.<\/p>\n<p>Tu bono sobre recibo referente a OneCasino consiste sobre algun bono por deposito del 11\ufffd, que recibiras una vez que te registres, tu cuenta haya sido verificada y no ha transpirado tras elaborar nuestro primer tanque. Levante exigencia se va a apoyar sobre el silli\ufffdn solicita unicamente dentro del monto del bono sin tanque. Es asi que que todo el mundo todos los jugadores adiconan semanalmente tiradas sin cargo de participar desplazandolo hacia el pelo gozar sobre todos los mejores juegos de casino; igualmente alguna cual una diferente sobresalto con el fin de fechas especificas.<\/p>\n<p>Los casinos con manga larga bonos sin deposito deben sentido fiable de empezar dentro del casino en internet en Portugal. Sin embargo los bonos desprovisto deposito son la excepcional vez para competir falto peligro, muchos usuarios cometen errores que les impiden aprovecharlos en el extremo o arrinconar las ganancias. Con el fin de aprovechar al extremo tu habilidad acerca de un casino en internet que usan bono falto deposito continua aquellos opiniones practicos asi\ufffd como aumenta las alternativas sobre convertirlo acerca de dinero eficaz.<\/p>\n<p>Por ejemplo, de eximir las ganancias de algun bono desprovisto tanque que usan algun capacidad de apuesta de 30 veces (x30), nuestro deportista tendra encontrarse apostado antiguamente 30 veces el valor de el bono. Algun factor fundamental a reflexionar alrededor del utilizar en los casinos las bonos de recibimiento regalado sin tanque es el conocido como rollover del bono, es bien existen demas juegos sobre casino en linea cual posibilitan esa bono de casino. Por lo general, los bonos sobre casino sin deposito estaran restringidos para cuando un competidor cual uso un bono falto tanque sobre el ultima especie. En caso de que quieres mas alternativas sumado a los bonos sin tanque, explora la coleccion sobre casinos joviales tiradas de balde y no ha transpirado bonos de casino carente tanque.<\/p>\n<p>Por eso desde Gambing Portugal recomendamos asentir y solicitar las bonos falto deposito. Una oferta sobre juegos de retar con los bonos carente tanque pude ser amplia, con las maquinas tragaperras igual que principal senuelo. Iniciar en jugar sobre algun casino con el pasar del tiempo cualquier bono carente tanque es una gigantesco opinion, sin embargo nunca invariablemente es posible por motivo de que son extremadamente pocos las casinos que cuentan con esta promociones. Buscamos bonos falto tanque cual cuenten con una proposicion gran sobre estrategias sobre retirada cuando nuestro componente logre soltar nuestro recursos de el bono.<\/p>","protected":false},"excerpt":{"rendered":"<p>Generalmente, suele suponer una tristeza solicitar las bonos desprovisto deposito, ya que ofrecen una alternativa de colocar acerca de juegos de casino de paga carente necesidad sobre elaborar ningun tanque. Las bonos sobre recibo sin tanque son extremadamente utilizadas en Portugal bien por cada ventajas que se fabrican con en contraposicion que usan otros bonos &#8230; <a title=\"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito\" class=\"read-more\" href=\"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/\" aria-label=\"Read more about En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito\">Read more<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-127432","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito - Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300\ufffd-en-bonos-de-casino-sin-deposito\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito\" \/>\n<meta property=\"og:description\" content=\"Generalmente, suele suponer una tristeza solicitar las bonos desprovisto deposito, ya que ofrecen una alternativa de colocar acerca de juegos de casino de paga carente necesidad sobre elaborar ningun tanque. Las bonos sobre recibo sin tanque son extremadamente utilizadas en Portugal bien por cada ventajas que se fabrican con en contraposicion que usan otros bonos ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300\ufffd-en-bonos-de-casino-sin-deposito\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-31T21:04:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T21:04:52+00:00\" \/>\n<meta name=\"author\" content=\"Nx_6ab509f5329c\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nx_6ab509f5329c\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/\"},\"author\":{\"name\":\"Nx_6ab509f5329c\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/#\\\/schema\\\/person\\\/520ecdccb9e03db4513835073149424a\"},\"headline\":\"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito\",\"datePublished\":\"2026-08-31T21:04:50+00:00\",\"dateModified\":\"2026-08-31T21:04:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/\"},\"wordCount\":1005,\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/\",\"url\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/\",\"name\":\"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito - Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/snlegal.hu\\\/#website\"},\"datePublished\":\"2026-08-31T21:04:50+00:00\",\"dateModified\":\"2026-08-31T21:04:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/snlegal.hu\\\/#\\\/schema\\\/person\\\/520ecdccb9e03db4513835073149424a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/snlegal.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/#website\",\"url\":\"https:\\\/\\\/snlegal.hu\\\/\",\"name\":\"Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/snlegal.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/snlegal.hu\\\/#\\\/schema\\\/person\\\/520ecdccb9e03db4513835073149424a\",\"name\":\"Nx_6ab509f5329c\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g\",\"caption\":\"Nx_6ab509f5329c\"},\"url\":\"https:\\\/\\\/snlegal.hu\\\/en\\\/author\\\/nx_6ab509f5329c\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito - Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300\ufffd-en-bonos-de-casino-sin-deposito\/","og_locale":"en_GB","og_type":"article","og_title":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito","og_description":"Generalmente, suele suponer una tristeza solicitar las bonos desprovisto deposito, ya que ofrecen una alternativa de colocar acerca de juegos de casino de paga carente necesidad sobre elaborar ningun tanque. Las bonos sobre recibo sin tanque son extremadamente utilizadas en Portugal bien por cada ventajas que se fabrican con en contraposicion que usan otros bonos ... Read more","og_url":"https:\/\/snlegal.hu\/en\/en-integro-puedes-conseguir-alguna-300\ufffd-en-bonos-de-casino-sin-deposito\/","og_site_name":"Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s","article_published_time":"2026-08-31T21:04:50+00:00","article_modified_time":"2026-08-31T21:04:52+00:00","author":"Nx_6ab509f5329c","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nx_6ab509f5329c","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/#article","isPartOf":{"@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/"},"author":{"name":"Nx_6ab509f5329c","@id":"https:\/\/snlegal.hu\/#\/schema\/person\/520ecdccb9e03db4513835073149424a"},"headline":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito","datePublished":"2026-08-31T21:04:50+00:00","dateModified":"2026-08-31T21:04:52+00:00","mainEntityOfPage":{"@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/"},"wordCount":1005,"articleSection":["Uncategorized"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/","url":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/","name":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito - Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s","isPartOf":{"@id":"https:\/\/snlegal.hu\/#website"},"datePublished":"2026-08-31T21:04:50+00:00","dateModified":"2026-08-31T21:04:52+00:00","author":{"@id":"https:\/\/snlegal.hu\/#\/schema\/person\/520ecdccb9e03db4513835073149424a"},"breadcrumb":{"@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/snlegal.hu\/en-integro-puedes-conseguir-alguna-300%ef%bf%bd-en-bonos-de-casino-sin-deposito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/snlegal.hu\/"},{"@type":"ListItem","position":2,"name":"En integro, puedes conseguir alguna 300\ufffd en bonos de casino sin deposito"}]},{"@type":"WebSite","@id":"https:\/\/snlegal.hu\/#website","url":"https:\/\/snlegal.hu\/","name":"Dr. Sim\u00e1nyi Zsolt &amp; Dr. N\u00e9very P\u00e9ter \u00dcgyv\u00e9di T\u00e1rsul\u00e1s","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/snlegal.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/snlegal.hu\/#\/schema\/person\/520ecdccb9e03db4513835073149424a","name":"Nx_6ab509f5329c","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3ab292c1422dd8df62f2869cd6a692fd6112b5c779024081e9afffba3d59505?s=96&d=mm&r=g","caption":"Nx_6ab509f5329c"},"url":"https:\/\/snlegal.hu\/en\/author\/nx_6ab509f5329c\/"}]}},"_links":{"self":[{"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/posts\/127432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/comments?post=127432"}],"version-history":[{"count":1,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/posts\/127432\/revisions"}],"predecessor-version":[{"id":127433,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/posts\/127432\/revisions\/127433"}],"wp:attachment":[{"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/media?parent=127432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/categories?post=127432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snlegal.hu\/en\/wp-json\/wp\/v2\/tags?post=127432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}